{"id":21843,"date":"2025-03-18T08:40:49","date_gmt":"2025-03-18T07:40:49","guid":{"rendered":"https:\/\/www.activemind.legal\/?p=21843"},"modified":"2025-03-18T08:42:55","modified_gmt":"2025-03-18T07:42:55","slug":"urteil-betriebsrat-ki","status":"publish","type":"post","link":"https:\/\/www.activemind.legal\/de\/guides\/urteil-betriebsrat-ki\/","title":{"rendered":"Darf Betriebsrat bei Einf\u00fchrung von KI mitreden?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"21843\" class=\"elementor elementor-21843\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0ed2f61 e-flex e-con-boxed e-con e-parent\" data-id=\"0ed2f61\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e5dbc67 elementor-widget elementor-widget-text-editor\" data-id=\"e5dbc67\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Integration von <a href=\"https:\/\/www.activemind.legal\/de\/ki\/\">k\u00fcnstlicher Intelligenz (KI)<\/a> in den Arbeitsalltag sorgt immer wieder f\u00fcr Diskussionen, vor allem zwischen Arbeitgebern und Betriebsr\u00e4ten. Arbeitnehmervertreter begegnen den aufgestellten Versprechen von Effizienzsteigerung und Innovation oft mit Skepsis. Bef\u00fcrchtungen \u00fcber eine m\u00f6gliche Kontrolle und \u00dcberwachung der Belegschaft sowie Unsicherheiten \u00fcber datenschutzrechtliche Aspekte pr\u00e4gen den Diskurs. <\/p><p>Ein wesentlicher Streitpunkt ist dabei, ob und in welchem Umfang Betriebsr\u00e4te ein Mitbestimmungsrecht bei der Einf\u00fchrung von KI-Systemen haben. Dazu hat nun das Arbeitsgericht (ArbG) Hamburg ein aufschlussreiches Urteil erlassen (Urteil vom 16. Januar 2024, Az: <a href=\"https:\/\/www.landesrecht-hamburg.de\/bsha\/document\/NJRE001564562\" target=\"_blank\" rel=\"noopener nofollow\">24 BVGa 1\/24)<\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a5969c6 elementor-widget elementor-widget-text-editor\" data-id=\"a5969c6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Hintergrund: Mitbestimmungsrecht des Betriebsrats<\/h2><p>Der Betriebsrat spielt eine bedeutende Rolle bei der Wahrung von Arbeitnehmerinteressen. Ein wesentliches Instrument, das ihm dabei zur Verf\u00fcgung steht, ist das Mitbestimmungsrecht gem\u00e4\u00df \u00a7 87 Betriebsverfassungsgesetz (BetrVG).<\/p><p>Nach \u00a7 87 Abs. 1 Nr. 1 BetrVG besitzt der Betriebsrat das Recht, in Angelegenheiten der Betriebsordnung und des Verhaltens der Mitarbeiter mitzuwirken. Dieses Recht sichert den Betriebsr\u00e4ten Einfluss auf Regelungen, die das betriebliche Zusammenleben ber\u00fchren. Es erstreckt sich auf Ma\u00dfnahmen, die das sogenannte Ordnungsverhalten der Besch\u00e4ftigten betreffen, also Regelungen, die auf die Gestaltung des kollektiven Miteinanders abzielen.<\/p><p>Allerdings ist das Mitbestimmungsrecht begrenzt. Es umfasst keine Ma\u00dfnahmen, die nur das Arbeitsverhalten der Arbeitnehmer betreffen \u2013 wie etwa Weisungen dazu, welche konkreten Aufgaben auszuf\u00fchren und wie diese zu erledigen sind. Jedoch f\u00e4llt es oft schwer, diese Unterscheidung zwischen Ordnungsverhalten und Arbeitsverhalten zu treffen, vor allem bei modernen Technologien wie KI, die gravierende \u00c4nderungen in den Arbeitsabl\u00e4ufen bewirken k\u00f6nnen.<\/p><p>Neben \u00a7 87 Abs. Nr. 1 BetrVG gibt es noch weitere F\u00e4lle, in denen dem Betriebstrat ein Mitbestimmungsrecht zukommt. Wichtig dabei ist \u00a7 87 Abs. 1 Nr. 6 BetrVG, wonach ein Mitbestimmungsrecht des Betriebsrates bei der Einf\u00fchrung und Anwendung von technischen Einrichtungen besteht, die dazu bestimmt sind, das Verhalten oder die Leistung der Arbeitnehmer zu \u00fcberwachen.<\/p><h2>Der Fall: Unternehmen f\u00fchrt KI-Richtlinien ein<\/h2><p>Ein Unternehmen hatte interne Richtlinien zur Nutzung von KI ver\u00f6ffentlicht. Konkret ging es um Anweisungen im Umgang mit generativer KI, wie ChatGPT.<\/p><p>Der Betriebsrat kritisierte diese Einf\u00fchrung scharf. Er sah seine Mitbestimmungsrechte verletzt und forderte, die Nutzung von ChatGPT bis zum Abschluss einer konzernweiten Betriebsvereinbarung auszusetzen.<\/p><ul><li>Nach Auffassung des Betriebsrats handelte es sich um einen groben Eingriff in seine Rechte aus \u00a7 87 Abs. 1 Nr. 1, Nr. 6 und Nr. 7 BetrVG, da durch die KI-Nutzung sowohl das Ordnungsverhalten der Arbeitnehmer als auch der Datenschutz ber\u00fchrt w\u00fcrden.<\/li><li>Zudem bef\u00fcrchtete der Betriebsrat eine Spaltung der Belegschaft in KI-Bef\u00fcrworter und -Skeptiker, was das Betriebsklima belasten k\u00f6nnte.<\/li><\/ul><p>Die Arbeitgeberin hingegen bestritt jegliche Mitbestimmungspflicht. Sie f\u00fchrte an, dass die Nutzung der KI-Tools f\u00fcr die Arbeitnehmer freiwillig sei und daher keinen \u00dcberwachungsdruck erzeugen k\u00f6nne. Weiterhin betonte sie, dass keine technische M\u00f6glichkeit bestehe, durch ChatGPT das Verhalten oder die Leistung der Mitarbeiter zu \u00fcberwachen. Dar\u00fcber hinaus legte die Arbeitgeberin eine <a href=\"https:\/\/www.activemind.legal\/de\/datenschutz\/dsfa\/\">Datenschutz-Folgenabsch\u00e4tzung (DSFA)<\/a> vor, um die datenschutzrechtlichen Bedenken auszur\u00e4umen und betonte dabei, dass die KI-Richtlinien lediglich als Handlungsempfehlungen zu verstehen sind.<\/p><h2>Beschluss des Arbeitsgerichts Hamburg<\/h2><p>Das ArbG Hamburg lehnte die Antr\u00e4ge des Betriebsrats ab. Nach eingehender Pr\u00fcfung kam das Gericht zu dem Schluss, dass die Einf\u00fchrung der KI-Richtlinien und die Nutzung von ChatGPT keine Mitbestimmungspflicht ausl\u00f6sen.<\/p><h3>Arbeits- oder Ordnungsverhalten (\u00a7 87 Abs. 1 Nr. 1 BetrVG)<\/h3><p>Das Gericht erkl\u00e4rte, dass die Nutzung von ChatGPT lediglich die Art und Weise der Arbeitsausf\u00fchrung betreffe und somit das mitbestimmungsfreie Arbeitsverhalten ber\u00fchre. Das Ordnungsverhalten, das die betriebliche Mitbestimmung erfordern w\u00fcrde, sei hingegen nicht betroffen. Die vom Betriebsrat vorgebrachte Argumentation, dass die Nutzung von ChatGPT die Arbeitnehmer in zwei Gruppen \u2013 KI-Nutzer und KI-Verweigerer \u2013 spalte, \u00fcberzeugte die Richter nicht. Diese Dynamik sei typisch f\u00fcr die Einf\u00fchrung neuer Arbeitsmittel und begr\u00fcnde kein Mitbestimmungsrecht.<\/p><h3>\u00dcberwachung durch technische Einrichtungen (\u00a7 87 Abs. 1 Nr. 6 BetrVG)<\/h3><p>Ein weiterer zentraler Punkt des Urteils war die Frage, ob ChatGPT als eine technische Einrichtung im Sinne von \u00a7 87 Abs. 1 Nr. 6 BetrVG zu betrachten ist, die zur \u00dcberwachung der Arbeitnehmer eingesetzt werden kann. Nach der Rechtsprechung liegt ein \u00dcberwachungstatbestand nur dann vor, wenn die technische Einrichtung objektiv dazu geeignet ist, Informationen \u00fcber Verhalten oder Leistung der Besch\u00e4ftigten zu sammeln, zu speichern oder weiterzuverarbeiten.<\/p><p>In diesem Fall stellte das Gericht fest, dass f\u00fcr die Arbeitgeberin keinerlei Zugriffsm\u00f6glichkeiten auf die mittels KI generierten Daten bestehe. ChatGPT erf\u00fclle keine solche \u00dcberwachungsfunktion, da die Besch\u00e4ftigen ChatGPT ausschlie\u00dflich \u00fcber ihre privaten Accounts verwenden durften. Somit sei auch kein Mitbestimmungsrecht nach \u00a7 87 Abs. 1 Nr. 6 BetrVG gegeben, da die Arbeitgeberin mittels ChatGPT keine Daten erheben oder speichern k\u00f6nne, die das Verhalten oder die Leistung der Besch\u00e4ftigten erfasst.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72f40b8 elementor-widget elementor-widget-text-editor\" data-id=\"72f40b8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Tipp:<\/strong> Lesen Sie zum <a href=\"https:\/\/www.activemind.de\/magazin\/byoai\/\" target=\"_blank\" rel=\"noopener\">Einsatz privater Zug\u00e4nge von KI-Tools im beruflichen Kontext den Ratgeber zum Thema Bring Your Own AI (BYOAI)<\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f2ba38 elementor-widget elementor-widget-text-editor\" data-id=\"8f2ba38\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Gef\u00e4hrdung der Mitarbeitenden (\u00a7 87 Abs. 1 Nr. 7 BetrVG)<\/h3><p>F\u00fcr ein Mitbestimmungsrecht nach \u00a7 87 Abs. 1 Nr. 7 BetrVG w\u00e4re der Nachweis einer konkreten Gef\u00e4hrdung der Arbeitnehmer erforderlich gewesen, etwa durch eine Gef\u00e4hrdungsbeurteilung nach dem Arbeitsschutzgesetz. Der Betriebsrat konnte jedoch keine solchen Gef\u00e4hrdungen vortragen, und das Gericht wies darauf hin, dass solche auch nicht erkennbar seien.<\/p><h2>Fazit<\/h2><p>Der Beschluss des ArbG Hamburg bietet einen Einblick in die rechtlichen Herausforderungen, die mit der Einf\u00fchrung von KI-Systemen am Arbeitsplatz verbunden sind. Er verdeutlicht, dass die Mitbestimmung des Betriebsrats von den spezifischen Umst\u00e4nden des Einzelfalls abh\u00e4ngt. Im vorliegenden Fall war die Nutzung von ChatGPT freiwillig, erfolgte ohne firmeneigene Installation und ohne Zugriff des Arbeitgebers auf verarbeitete Daten.<\/p><p>Es sind jedoch abweichende Konstellationen denkbar, etwa wenn der Arbeitgeber Zugriff auf die mittels KI-System verarbeiteten Daten hat oder gar ein KI-System zur Bewertung der Mitarbeitendenleistung einsetzt (Stichwort: <a href=\"https:\/\/www.activemind.legal\/de\/guides\/ki-automatisierte-entscheidungen\/\">automatisierte Entscheidungsfindung mit KI<\/a>), die zu anderen rechtlichen Bewertungen f\u00fchren k\u00f6nnen.<\/p><p>Damit besteht weiterhin ein Spannungsfeld zwischen technologischer Innovation und betrieblicher Mitbestimmung. Die rechtliche Auseinandersetzung k\u00f6nnte langfristig zu neuen Standards f\u00fchren, die den Umgang mit KI am Arbeitsplatz regeln.<\/p><p>Zudem kommt auf Arbeitgeber, die nach dem <a href=\"https:\/\/www.activemind.legal\/de\/guides\/ai-act\/\">AI Act<\/a> als Betreiber eines Hochrisiko-KI\u2011Systems am Arbeitsplatz einzustufen sind, eine neue Pflicht zu. Nach <a href=\"https:\/\/www.activemind.legal\/de\/gesetze\/ai-act\/artikel-26\/\">Art. 26 Abs. 7 AI Act<\/a> werden Unternehmen in einem solchen Fall verpflichtet, die Arbeitnehmervertreter und die betroffenen Arbeitnehmer dar\u00fcber zu informieren, dass sie der Verwendung des Hochrisiko-KI\u2011Systems unterliegen werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cbca75b elementor-cta--layout-image-left elementor-cta--valign-middle kl-cta elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-global elementor-global-18149 elementor-widget-call-to-action\" data-id=\"cbca75b\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/www.activemind.legal\/wp-content\/uploads\/activemind-mitarbeiter-10_quadrat_a.jpg);\" role=\"img\" aria-label=\"An data protection expoert of activeMind.legal stands in front of his team\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tSch\u00fctzen Sie Ihr Business\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tProfitieren Sie von unserer Rechtsberatung in den Bereichen Datenschutz, IT und Compliance. \t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item \">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"\/de\/rechtsberatung\/\" title=\"Individuelle Rechtsberatung f\u00fcr Unternehmen\">\n\t\t\t\t\t\tLernen Sie uns kennen!\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Das Arbeitsgericht Hamburg urteilt, ob das Mitbestimmungsrecht des Betriebsrats bei der Einf\u00fchrung von Richtlinien zur KI-Nutzung greift. <\/p>\n","protected":false},"author":52,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[104,45],"tags":[],"class_list":["post-21843","post","type-post","status-publish","format-standard","hentry","category-ki","category-urteile"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Darf Betriebsrat bei Einf\u00fchrung von KI mitreden? | activeMind.legal<\/title>\n<meta name=\"description\" content=\"Das Arbeitsgericht Hamburg urteilt, ob das Mitbestimmungsrecht des Betriebsrats bei der Einf\u00fchrung von Richtlinien zur KI-Nutzung greift.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.activemind.legal\/de\/guides\/urteil-betriebsrat-ki\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Darf Betriebsrat bei Einf\u00fchrung von KI mitreden? | activeMind.legal\" \/>\n<meta property=\"og:description\" content=\"Das Arbeitsgericht Hamburg urteilt, ob das Mitbestimmungsrecht des Betriebsrats bei der Einf\u00fchrung von Richtlinien zur KI-Nutzung greift.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.activemind.legal\/de\/guides\/urteil-betriebsrat-ki\/\" \/>\n<meta property=\"og:site_name\" content=\"activeMind.legal\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-18T07:40:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-18T07:42:55+00:00\" \/>\n<meta name=\"author\" content=\"Nicole Kopp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicole Kopp\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.activemind.legal\\\/de\\\/guides\\\/urteil-betriebsrat-ki\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.activemind.legal\\\/de\\\/guides\\\/urteil-betriebsrat-ki\\\/\"},\"author\":{\"name\":\"Nicole Kopp\",\"@id\":\"https:\\\/\\\/www.activemind.legal\\\/de\\\/#\\\/schema\\\/person\\\/acc07d7ef8a579d083a1da91e6fb9c87\"},\"headline\":\"Darf Betriebsrat bei Einf\u00fchrung von KI mitreden?\",\"datePublished\":\"2025-03-18T07:40:49+00:00\",\"dateModified\":\"2025-03-18T07:42:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.activemind.legal\\\/de\\\/guides\\\/urteil-betriebsrat-ki\\\/\"},\"wordCount\":1042,\"publisher\":{\"@id\":\"https:\\\/\\\/www.activemind.legal\\\/de\\\/#organization\"},\"articleSection\":[\"K\u00fcnstliche Intelligenz (KI)\",\"Urteile\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.activemind.legal\\\/de\\\/guides\\\/urteil-betriebsrat-ki\\\/\",\"url\":\"https:\\\/\\\/www.activemind.legal\\\/de\\\/guides\\\/urteil-betriebsrat-ki\\\/\",\"name\":\"Darf Betriebsrat bei Einf\u00fchrung von KI mitreden? | activeMind.legal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.activemind.legal\\\/de\\\/#website\"},\"datePublished\":\"2025-03-18T07:40:49+00:00\",\"dateModified\":\"2025-03-18T07:42:55+00:00\",\"description\":\"Das Arbeitsgericht Hamburg urteilt, ob das Mitbestimmungsrecht des Betriebsrats bei der Einf\u00fchrung von Richtlinien zur KI-Nutzung greift.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.activemind.legal\\\/de\\\/guides\\\/urteil-betriebsrat-ki\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.activemind.legal\\\/de\\\/guides\\\/urteil-betriebsrat-ki\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.activemind.legal\\\/de\\\/guides\\\/urteil-betriebsrat-ki\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.activemind.legal\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Urteil KI-Richtlinien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.activemind.legal\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.activemind.legal\\\/de\\\/\",\"name\":\"activeMind.legal\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.activemind.legal\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.activemind.legal\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.activemind.legal\\\/de\\\/#organization\",\"name\":\"activeMind.legal\",\"alternateName\":\"activeMind.legal Rechtsanwaltsgesellschaft mbH\",\"url\":\"https:\\\/\\\/www.activemind.legal\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.activemind.legal\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.activemind.legal\\\/wp-content\\\/uploads\\\/activeMind-legal_logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.activemind.legal\\\/wp-content\\\/uploads\\\/activeMind-legal_logo.svg\",\"caption\":\"activeMind.legal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.activemind.legal\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.activemind.legal\\\/de\\\/#\\\/schema\\\/person\\\/acc07d7ef8a579d083a1da91e6fb9c87\",\"name\":\"Nicole Kopp\",\"url\":\"https:\\\/\\\/www.activemind.legal\\\/de\\\/guides\\\/author\\\/nicolekopp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Darf Betriebsrat bei Einf\u00fchrung von KI mitreden? | activeMind.legal","description":"Das Arbeitsgericht Hamburg urteilt, ob das Mitbestimmungsrecht des Betriebsrats bei der Einf\u00fchrung von Richtlinien zur KI-Nutzung greift.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.activemind.legal\/de\/guides\/urteil-betriebsrat-ki\/","og_locale":"de_DE","og_type":"article","og_title":"Darf Betriebsrat bei Einf\u00fchrung von KI mitreden? | activeMind.legal","og_description":"Das Arbeitsgericht Hamburg urteilt, ob das Mitbestimmungsrecht des Betriebsrats bei der Einf\u00fchrung von Richtlinien zur KI-Nutzung greift.","og_url":"https:\/\/www.activemind.legal\/de\/guides\/urteil-betriebsrat-ki\/","og_site_name":"activeMind.legal","article_published_time":"2025-03-18T07:40:49+00:00","article_modified_time":"2025-03-18T07:42:55+00:00","author":"Nicole Kopp","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Nicole Kopp","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.activemind.legal\/de\/guides\/urteil-betriebsrat-ki\/#article","isPartOf":{"@id":"https:\/\/www.activemind.legal\/de\/guides\/urteil-betriebsrat-ki\/"},"author":{"name":"Nicole Kopp","@id":"https:\/\/www.activemind.legal\/de\/#\/schema\/person\/acc07d7ef8a579d083a1da91e6fb9c87"},"headline":"Darf Betriebsrat bei Einf\u00fchrung von KI mitreden?","datePublished":"2025-03-18T07:40:49+00:00","dateModified":"2025-03-18T07:42:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.activemind.legal\/de\/guides\/urteil-betriebsrat-ki\/"},"wordCount":1042,"publisher":{"@id":"https:\/\/www.activemind.legal\/de\/#organization"},"articleSection":["K\u00fcnstliche Intelligenz (KI)","Urteile"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/www.activemind.legal\/de\/guides\/urteil-betriebsrat-ki\/","url":"https:\/\/www.activemind.legal\/de\/guides\/urteil-betriebsrat-ki\/","name":"Darf Betriebsrat bei Einf\u00fchrung von KI mitreden? | activeMind.legal","isPartOf":{"@id":"https:\/\/www.activemind.legal\/de\/#website"},"datePublished":"2025-03-18T07:40:49+00:00","dateModified":"2025-03-18T07:42:55+00:00","description":"Das Arbeitsgericht Hamburg urteilt, ob das Mitbestimmungsrecht des Betriebsrats bei der Einf\u00fchrung von Richtlinien zur KI-Nutzung greift.","breadcrumb":{"@id":"https:\/\/www.activemind.legal\/de\/guides\/urteil-betriebsrat-ki\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.activemind.legal\/de\/guides\/urteil-betriebsrat-ki\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.activemind.legal\/de\/guides\/urteil-betriebsrat-ki\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.activemind.legal\/de\/"},{"@type":"ListItem","position":2,"name":"Urteil KI-Richtlinien"}]},{"@type":"WebSite","@id":"https:\/\/www.activemind.legal\/de\/#website","url":"https:\/\/www.activemind.legal\/de\/","name":"activeMind.legal","description":"","publisher":{"@id":"https:\/\/www.activemind.legal\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.activemind.legal\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.activemind.legal\/de\/#organization","name":"activeMind.legal","alternateName":"activeMind.legal Rechtsanwaltsgesellschaft mbH","url":"https:\/\/www.activemind.legal\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.activemind.legal\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.activemind.legal\/wp-content\/uploads\/activeMind-legal_logo.svg","contentUrl":"https:\/\/www.activemind.legal\/wp-content\/uploads\/activeMind-legal_logo.svg","caption":"activeMind.legal"},"image":{"@id":"https:\/\/www.activemind.legal\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.activemind.legal\/de\/#\/schema\/person\/acc07d7ef8a579d083a1da91e6fb9c87","name":"Nicole Kopp","url":"https:\/\/www.activemind.legal\/de\/guides\/author\/nicolekopp\/"}]}},"_links":{"self":[{"href":"https:\/\/www.activemind.legal\/de\/wp-json\/wp\/v2\/posts\/21843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.activemind.legal\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.activemind.legal\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.activemind.legal\/de\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/www.activemind.legal\/de\/wp-json\/wp\/v2\/comments?post=21843"}],"version-history":[{"count":8,"href":"https:\/\/www.activemind.legal\/de\/wp-json\/wp\/v2\/posts\/21843\/revisions"}],"predecessor-version":[{"id":21851,"href":"https:\/\/www.activemind.legal\/de\/wp-json\/wp\/v2\/posts\/21843\/revisions\/21851"}],"wp:attachment":[{"href":"https:\/\/www.activemind.legal\/de\/wp-json\/wp\/v2\/media?parent=21843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.activemind.legal\/de\/wp-json\/wp\/v2\/categories?post=21843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.activemind.legal\/de\/wp-json\/wp\/v2\/tags?post=21843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}